﻿{"id":123,"date":"2018-07-24T23:27:39","date_gmt":"2018-07-24T21:27:39","guid":{"rendered":"http:\/\/pd.rolfcaviezel.ch\/?page_id=123"},"modified":"2018-09-26T21:27:24","modified_gmt":"2018-09-26T19:27:24","slug":"glossarerstellung","status":"publish","type":"page","link":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/glossarerstellung\/","title":{"rendered":"Elavuraziun da glossari"},"content":{"rendered":"<p>Sin giavisch poss jau leger tras Voss texts e far cun las expressiuns tecnicas in glossari.<\/p>\n<table>\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"604\"><strong>Tariffas<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"302\">Tariffa per ura<\/td>\n<td width=\"302\">CHF 70.00<\/td>\n<\/tr>\n<tr>\n<td width=\"302\">Pauschala minimala<\/td>\n<td width=\"302\">CHF 17.50<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Sin giavisch poss jau leger tras Voss texts e far cun las expressiuns tecnicas in glossari. Tariffas Tariffa per ura CHF 70.00 Pauschala minimala CHF 17.50<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-123","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"rm","enabled_languages":["de","rm","fr","gb"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"rm":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"gb":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/pages\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/comments?post=123"}],"version-history":[{"count":13,"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/pages\/123\/revisions"}],"predecessor-version":[{"id":849,"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/pages\/123\/revisions\/849"}],"wp:attachment":[{"href":"https:\/\/xn--rtoromanische-bersetzungen-ghc99d.ch\/rm\/wp-json\/wp\/v2\/media?parent=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}